{"id":7092,"date":"2023-11-03T09:14:05","date_gmt":"2023-11-03T08:14:05","guid":{"rendered":"https:\/\/www.tkd-wolnzach.de\/blog\/?p=7092"},"modified":"2023-11-03T09:14:35","modified_gmt":"2023-11-03T08:14:35","slug":"kup-pruefung-am-10-12-2023","status":"publish","type":"post","link":"https:\/\/www.tkd-wolnzach.de\/blog\/allgemein\/kup-pruefung-am-10-12-2023","title":{"rendered":"Kup-Pr\u00fcfung am 10.12.2023"},"content":{"rendered":"\n<p>Unsere 2. Kup-Pr\u00fcfung findet am Sonntag, den 10. Dezember in der Kapuzinerhalle statt.<br \/>Eine zus\u00e4tzliche Vorpr\u00fcfung ist nicht erforderlich.<\/p>\n\n\n\n<p>Einhaltung der in der aktuellen Pr\u00fcfungsordnung der Deutschen Taekwondo Union genannten Wartezeiten, sowie die Erf\u00fcllung der erforderlichen Trainingseinheiten sind die Voraussetzungen f\u00fcr eine Teilnahme an der G\u00fcrtelpr\u00fcfung.<br \/>Die Anmeldung zur Pr\u00fcfung muss bis sp\u00e4testens 23.11.2023 bei einem Trainer erfolgen.<br \/>Von allen Wei\u00dfg\u00fcrteln (10. Kup) ben\u00f6tigen wir zus\u00e4tzlich bis zum 23.11.2023 ein aktuelles Passbild. Die Pr\u00fcfungsgeb\u00fchr von 15,- EUR kann gerne auch vorab bei den Trainern oder dann am Pr\u00fcfungstag bezahlt werden.<br \/>Die Anmeldung ist verbindlich! Bei Nichtbestehen der Pr\u00fcfung oder Nichtteilnahme kann die Pr\u00fcfungsgeb\u00fchr nicht zur\u00fcckerstattet werden.<\/p>\n\n\n\n<p><br \/>Zeitplan zur G\u00fcrtelpr\u00fcfung am Sonntag, den 10.12.2023 in der Kapuzinerhalle:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Hallen\u00f6ffnung ab 9:30 Uhr f\u00fcr <strong>alle Kup-Grade <\/strong><\/li>\n\n\n\n<li>Pr\u00fcfungsbeginn <strong>ab 10:00 Uhr<\/strong><br \/><\/li>\n<\/ul>\n\n\n\n<p>Wir w\u00fcnschen euch viel Erfolg\u2026<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unsere 2. Kup-Pr\u00fcfung findet am Sonntag, den 10. Dezember in der Kapuzinerhalle statt.Eine zus\u00e4tzliche Vorpr\u00fcfung ist nicht erforderlich. Einhaltung der in der aktuellen Pr\u00fcfungsordnung der Deutschen Taekwondo Union genannten Wartezeiten, sowie die Erf\u00fcllung der erforderlichen Trainingseinheiten sind die Voraussetzungen f\u00fcr eine Teilnahme an der G\u00fcrtelpr\u00fcfung.Die Anmeldung zur Pr\u00fcfung muss bis sp\u00e4testens 23.11.2023 bei einem Trainer [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7092","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.tkd-wolnzach.de\/blog\/wp-json\/wp\/v2\/posts\/7092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tkd-wolnzach.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tkd-wolnzach.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tkd-wolnzach.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tkd-wolnzach.de\/blog\/wp-json\/wp\/v2\/comments?post=7092"}],"version-history":[{"count":2,"href":"https:\/\/www.tkd-wolnzach.de\/blog\/wp-json\/wp\/v2\/posts\/7092\/revisions"}],"predecessor-version":[{"id":7094,"href":"https:\/\/www.tkd-wolnzach.de\/blog\/wp-json\/wp\/v2\/posts\/7092\/revisions\/7094"}],"wp:attachment":[{"href":"https:\/\/www.tkd-wolnzach.de\/blog\/wp-json\/wp\/v2\/media?parent=7092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tkd-wolnzach.de\/blog\/wp-json\/wp\/v2\/categories?post=7092"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tkd-wolnzach.de\/blog\/wp-json\/wp\/v2\/tags?post=7092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}